{"id":5193,"date":"2025-08-13T17:26:12","date_gmt":"2025-08-13T17:26:12","guid":{"rendered":"https:\/\/csiglobal.com\/proyectos\/access-to-sarandi-del-yi-route-6\/"},"modified":"2026-04-20T19:23:50","modified_gmt":"2026-04-20T19:23:50","slug":"access-to-sarandi-del-yi-route-6","status":"publish","type":"proyectos","link":"https:\/\/csiglobal.com\/en\/projects\/access-to-sarandi-del-yi-route-6\/","title":{"rendered":"Access to Sarand\u00ed del Y\u00ed, Route 6"},"content":{"rendered":"","protected":false},"featured_media":5194,"parent":0,"template":"","filtro-pais":[],"filtro-sector":[48],"class_list":["post-5193","proyectos","type-proyectos","status-publish","has-post-thumbnail","hentry","filtro-sector-transportation-infrastructure"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/proyectos\/5193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/proyectos"}],"about":[{"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/types\/proyectos"}],"version-history":[{"count":1,"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/proyectos\/5193\/revisions"}],"predecessor-version":[{"id":5506,"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/proyectos\/5193\/revisions\/5506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/media\/5194"}],"wp:attachment":[{"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/media?parent=5193"}],"wp:term":[{"taxonomy":"filtro-pais","embeddable":true,"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/filtro-pais?post=5193"},{"taxonomy":"filtro-sector","embeddable":true,"href":"https:\/\/csiglobal.com\/en\/wp-json\/wp\/v2\/filtro-sector?post=5193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}